{"id":12458,"date":"2023-12-01T09:38:19","date_gmt":"2023-12-01T08:38:19","guid":{"rendered":"https:\/\/dagyvintage.com\/?post_type=product&#038;p=12458"},"modified":"2024-02-17T10:46:16","modified_gmt":"2024-02-17T09:46:16","slug":"coat-in-cotton-and-wool","status":"publish","type":"product","link":"https:\/\/dagyvintage.com\/it\/negozio\/coat-in-cotton-and-wool\/","title":{"rendered":"CAPPOTTO IN COTONE E LANA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Cappotto di Miu Miu, linea giovane di Prada. Esternamente il capo \u00e8 in cotone colore verde militare, internamente invece rivestito in leggera lana color grigio. Forma sfiancata e femminile. Dettagli militari sulle spalle e sul retro del cappotto. Purtroppo l'etichetta della composizione a causa del lavaggio si \u00e8 sbiadita. Taglia riportata 40 italiana, veste tranquillamente anche una 42 italiana. Condizioni ottime, nulla da segnalare.\u00a0<\/p>\n<p>MISURE<\/p>\n<ul>\n<li>LUNGHEZZA : 93 CM<\/li>\n<li>SPALLE : 40 CM<\/li>\n<li>TORACE : 45 CM<\/li>\n<li>LUNGHEZZA MANICHE : 65 CM<\/li>\n<\/ul>","protected":false},"featured_media":12459,"template":"","meta":[],"pwb-brand":[269],"product_cat":[68,69,74],"product_tag":[],"brands":[{"id":269,"name":"MIU MIU","slug":"miu-miu"}],"_links":{"self":[{"href":"https:\/\/dagyvintage.com\/it\/wp-json\/wp\/v2\/product\/12458"}],"collection":[{"href":"https:\/\/dagyvintage.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dagyvintage.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dagyvintage.com\/it\/wp-json\/wp\/v2\/media\/12459"}],"wp:attachment":[{"href":"https:\/\/dagyvintage.com\/it\/wp-json\/wp\/v2\/media?parent=12458"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/dagyvintage.com\/it\/wp-json\/wp\/v2\/pwb-brand?post=12458"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dagyvintage.com\/it\/wp-json\/wp\/v2\/product_cat?post=12458"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dagyvintage.com\/it\/wp-json\/wp\/v2\/product_tag?post=12458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}